{"id":1664,"date":"2021-07-04T14:15:08","date_gmt":"2021-07-04T12:15:08","guid":{"rendered":"https:\/\/www.chinaimbisstrier.de\/?page_id=1664"},"modified":"2026-07-12T23:41:23","modified_gmt":"2026-07-12T21:41:23","slug":"spezialitaeten","status":"publish","type":"page","link":"https:\/\/www.chopsticks-trier.de\/index.php\/spezialitaeten\/","title":{"rendered":"Spezialit\u00e4ten"},"content":{"rendered":"\n<p class=\"has-text-align-center has-black-color has-text-color\"><strong>40. Chopsticks Spezial \ud83c\udf36\ufe0f\ud83c\udf36\ufe0f\ud83c\udf36\ufe0f<\/strong><br>mit Huhn, Rind, Zwiebeln, Champignons, Spitzkohl, Zucchini<br>mit Reis (statt Reis mit Bratnudeln oder Eierreis + 2\u20ac)<br><strong>15,90 \u20ac<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-text-color\"><strong>41. San Sien gebraten<\/strong><br>mit Ente, H\u00fchner, Schweinefleisch &amp; Gem\u00fcse<br>mit Reis (statt Reis mit Bratnudeln oder Eierreis + 2\u20ac)<br><strong>13,90 \u20ac<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-text-color\"><strong>42. 8 Sch\u00e4tze (scharf) \ud83c\udf36\ufe0f<\/strong><br>mit Ente, Huhn, Schwein, Rind, Krabben &amp; Gem\u00fcse<br>mit Reis (statt Reis mit Bratnudeln oder Eierreis + 2\u20ac)<br><strong>13,90 \u20ac<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-text-color\"><strong>42a. 8 Sch\u00e4tze mit knuspriger Ente \ud83c\udf36\ufe0f<\/strong><br>mit Huhn, Schwein, Rind, Krabben &amp; Gem\u00fcse<br>mit Reis (statt Reis mit Bratnudeln oder Eierreis + 2\u20ac)<br><strong>16,90 \u20ac<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-text-color\"><strong>55. Mapo-Tofu \ud83c\udf36\ufe0f\ud83c\udf36\ufe0f<\/strong><br>mit Hackfleisch<br>mit Reis (statt Reis mit Bratnudeln oder Eierreis + 2\u20ac)<br><strong>14,90 \u20ac<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>40. Chopsticks Spezial \ud83c\udf36\ufe0f\ud83c\udf36\ufe0f\ud83c\udf36\ufe0fmit Huhn, Rind, Zwiebeln, Champignons, Spitzkohl, Zucchinimit Reis (statt Reis mit Bratnudeln oder Eierreis + 2\u20ac)15,90 \u20ac 41. San Sien gebratenmit Ente, [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.chopsticks-trier.de\/index.php\/wp-json\/wp\/v2\/pages\/1664"}],"collection":[{"href":"https:\/\/www.chopsticks-trier.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.chopsticks-trier.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.chopsticks-trier.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chopsticks-trier.de\/index.php\/wp-json\/wp\/v2\/comments?post=1664"}],"version-history":[{"count":42,"href":"https:\/\/www.chopsticks-trier.de\/index.php\/wp-json\/wp\/v2\/pages\/1664\/revisions"}],"predecessor-version":[{"id":2516,"href":"https:\/\/www.chopsticks-trier.de\/index.php\/wp-json\/wp\/v2\/pages\/1664\/revisions\/2516"}],"wp:attachment":[{"href":"https:\/\/www.chopsticks-trier.de\/index.php\/wp-json\/wp\/v2\/media?parent=1664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}